{"id":8684,"date":"2025-06-12T19:13:48","date_gmt":"2025-06-12T17:13:48","guid":{"rendered":"https:\/\/www.pipolcongres.eu\/?p=8684"},"modified":"2025-06-12T19:13:48","modified_gmt":"2025-06-12T17:13:48","slug":"la-famiglia-tra-reale-e-sembiante-guy-poblome","status":"publish","type":"post","link":"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/","title":{"rendered":"La famiglia, tra reale e sembiante &#8211; Guy Poblome"},"content":{"rendered":"<div class=\"pf-content\"><p class=\"tm10\"><span class=\"tm8\">Siamo solo a pochi passi dal congresso che si terr\u00e0 esattamente tra un mese, e l\u2019effervescenza dell\u2019alveare costituito dalle diverse commissioni di PIPOL 12 si fa sentire. I testi proposti al blog F<\/span><em><span class=\"tm11\">a<\/span><\/em><span class=\"tm8\">mil lo testimoniano. <\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Nella seconda parte di \u00ab\u00a0Il padre e la madre vaporizzati\u00a0\u00bb, Katty Langelez-Stevens ricorda innanzitutto come, una volta che il padre \u00e8 vaporizzato dal capitalismo, la famiglia si \u00e8 concentrata sulla coppia madre-bambino, dissociandola dal <\/span><em><span class=\"tm11\">conjugo<\/span><\/em><span class=\"tm8\">. K. Langelez-Stevens ritorna anche sul fatto che, come<\/span><s> <\/s><span class=\"tm8\">aveva indicato Jacques-Alain Miller durante il congresso PIPOL\u00a011, dopo essere stata un reale, la madre stessa, conseguenza del progresso della scienza, \u00e8 divenuta un sembiante. Il solo reale resta allora il bambino stesso, oggetto <\/span><em><span class=\"tm11\">a<\/span><\/em><span class=\"tm8\"> \u2013\u00a0potremmo dire oggetto pi\u00f9-di-godimento\u00a0?\u00a0\u2013 intorno al quale si costruisce la famiglia. <\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">\u00c8 ci\u00f2 che diceva Lacan, con uno stile inimitabile, quando diceva al suo auditorio che l\u2019oggetto <\/span><em><span class=\"tm11\">a<\/span><\/em><span class=\"tm8\"> \u201c\u00e8 ci\u00f2 che siamo ciascuno di noi, in quanto aborti di quello che \u00e8 stato, per coloro che ci hanno generato, causa di desiderio\u201d\u00a0[1]. Ma questo desiderio deve essere incarnato perch\u00e9 sia funzione di trasmissione per il bambino. \u00c8 ci\u00f2 che interroga Ruth Pinkasz facendo una differenza radicale tra quello che Lacan ha chiamato desiderio anonimo e la sua evocazione del mantenimento essenziale del mistero, dell\u2019enigma che presiede a questo desiderio, cos\u00ec che sia la funzione desiderante stessa che sar\u00e0 trasmessa. <\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Cos\u00ec, il bambino ha ancora la possibilit\u00e0 di occupare il posto del sintomo della verit\u00e0 della coppia dei suoi genitori. Altrimenti, sottomesso alle<\/span><span class=\"tm13\"> indagini di sviluppo neurologico<\/span><span class=\"tm8\">, diventa oggetto della scienza, come lo riprende Carina Arantes Faria a partire da una conferenza di Dominique Carpentier a proposito del lavoro al CPCT-Parents di Rennes. \u00c8 in tal modo esposto alla necessit\u00e0 di un <\/span><em><span class=\"tm11\">funziona<\/span><\/em><span class=\"tm8\">, producendo la cancellazione di un <\/span><em><span class=\"tm14\">non funziona.<\/span><\/em><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Ci\u00f2 che fa famiglia sarebbe un modo di godimento che vorremmo sia condivisibile, propone D.\u00a0Carpentier. Ma siamo obbligati a constatare che, come fa Aur\u00e9lia Verbecq, a proposito delle dipendenze negli adolescenti oggi, i godimenti sono sempre pi\u00f9 isolati. Le pratiche degli <\/span><em><span class=\"tm11\">Uni-tutti-soli <\/span><\/em><span class=\"tm8\">mettono in atto una rottura radicale con il campo dell\u2019Altro.<\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">\u00c8 dunque impossibile rispondere all\u2019imperativo <\/span><span class=\"tm13\">superegoico <\/span><span class=\"tm8\">del godimento\u00a0? Non \u00e8 la posizione della psicoanalisi. La sua scommessa \u00e8 di offrire una via, per colui che vuole intraprenderla, verso un\u2019invenzione che permetta di riaggiustare il rapporto del <\/span><em><span class=\"tm11\">parl\u00eatre<\/span><\/em><span class=\"tm8\"> al reale che colpisce.<\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Alcuni trovano altre soluzioni, come quella dell\u2019arte. Vanessa Mikowski ci presenta come la cineasta Chantal Akerman scriva, facendo perno su <\/span><em><span class=\"tm11\">lalingua <\/span><\/em><span class=\"tm8\">materna, come la sua famiglia si \u00e8 costituita intorno al vuoto di un reale, di un buco nella sua storia di cui la madre non ha potuto dire niente a sua figlia. Dal canto suo, il regista Hirokazu Kore-eda, come ne parla Isabelle Magne, mette in scena nel suo film <\/span><em><span class=\"tm11\">Le buone stelle-Broker<\/span><\/em><span class=\"tm8\">,<\/span> <span class=\"tm8\">l\u2019invenzione di una famiglia di sembianti intorno all\u2019irruzione di un neonato abbandonato. <\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Buona lettura e appuntamento a PIPOL\u00a0!<\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">\u00a0<\/span><\/p>\n<p class=\"tm10\"><span class=\"tm15\">[1]\u00a0<a id=\"aGoBack\"><\/a>J. Lacan <\/span><em><span class=\"tm16\">Il Seminario, Libro<\/span><\/em> <em><span class=\"tm16\">XVII,<\/span><\/em> <em><span class=\"tm16\">Il rovescio della psiconalisi <\/span><\/em><span class=\"tm15\">[1969-1970]<\/span><em><span class=\"tm16\">,<\/span><\/em><span class=\"tm15\"> Einaudi, Torino 2001.<\/span><\/p>\n<p class=\"tm18\"><span class=\"tm8\">\u00a0<\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Traduzione\u00a0: Elena Madera<\/span><\/p>\n<p class=\"tm10\"><span class=\"tm8\">Rilettura\u00a0: Michela Perini<\/span><\/p>\n<p class=\"tm18\"><span class=\"tm8\">\u00a0<\/span><\/p>\n<p class=\"Normal\">\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Siamo solo a pochi passi dal congresso che si terr\u00e0 esattamente tra un mese, e l\u2019effervescenza dell\u2019alveare costituito dalle diverse commissioni di PIPOL 12 si fa sentire. I testi proposti al blog Famil lo testimoniano. Nella seconda parte di \u00ab\u00a0Il padre e la madre vaporizzati\u00a0\u00bb, Katty Langelez-Stevens ricorda innanzitutto come, una volta che il padre [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[553],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La famiglia, tra reale e sembiante - Guy Poblome - Pipol Congr\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La famiglia, tra reale e sembiante - Guy Poblome - Pipol Congr\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Siamo solo a pochi passi dal congresso che si terr\u00e0 esattamente tra un mese, e l\u2019effervescenza dell\u2019alveare costituito dalle diverse commissioni di PIPOL 12 si fa sentire. I testi proposti al blog Famil lo testimoniano. Nella seconda parte di \u00ab\u00a0Il padre e la madre vaporizzati\u00a0\u00bb, Katty Langelez-Stevens ricorda innanzitutto come, una volta che il padre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/\" \/>\n<meta property=\"og:site_name\" content=\"Pipol Congr\u00e8s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/12D7tEQ44kL\/?mibextid=LQQJ4d\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-12T17:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pipolcongres.eu\/wp-content\/uploads\/2025\/06\/Blog-19.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"752\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data1\" content=\"2 minuti\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/#website\",\"url\":\"https:\/\/www.pipolcongres.eu\/it\/\",\"name\":\"Pipol Congr\\u00e8s\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.pipolcongres.eu\/it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.pipolcongres.eu\/wp-content\/uploads\/2025\/06\/Blog-19.jpeg\",\"width\":752,\"height\":370},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/#webpage\",\"url\":\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/\",\"name\":\"La famiglia, tra reale e sembiante - Guy Poblome - Pipol Congr\\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/#primaryimage\"},\"datePublished\":\"2025-06-12T17:13:48+00:00\",\"dateModified\":\"2025-06-12T17:13:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/#\/schema\/person\/f8cb217f45103fcb436f14acee2b5b9b\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pipolcongres.eu\/it\/2025\/06\/12\/la-famiglia-tra-reale-e-sembiante-guy-poblome\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/#\/schema\/person\/f8cb217f45103fcb436f14acee2b5b9b\",\"name\":\"PIPOL TEAM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pipolcongres.eu\/it\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b98e815813af2d80d5c2073a926d2dd2?s=96&d=mm&r=g\",\"caption\":\"PIPOL TEAM\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/posts\/8684"}],"collection":[{"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/comments?post=8684"}],"version-history":[{"count":1,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/posts\/8684\/revisions"}],"predecessor-version":[{"id":8685,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/posts\/8684\/revisions\/8685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/media\/8681"}],"wp:attachment":[{"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/media?parent=8684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/categories?post=8684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pipolcongres.eu\/it\/wp-json\/wp\/v2\/tags?post=8684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}